{"id":33,"date":"2025-11-27T21:32:40","date_gmt":"2025-11-27T21:32:40","guid":{"rendered":"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/index.php\/mesmerize\/"},"modified":"2026-03-23T16:56:29","modified_gmt":"2026-03-23T16:56:29","slug":"mesmerize","status":"publish","type":"page","link":"https:\/\/www.cielesondesmots.com\/","title":{"rendered":"Front Page"},"content":{"rendered":"<div  id=\"about-1\" class=\"about-1 content-section\" style=\"background-color: #ffffff;\" data-label=\"About\" data-id=\"about--1\" data-export-id=\"about-1\" data-category=\"about\">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">Cie Le Son des Mots<\/h2>\nUn th\u00e9\u00e2tre de sens\n\n<\/div>\n<\/div>\n<div  class=\"row\">\n<div  class=\"button-holder space-bottom space-bottom-small\" data-type=\"column\"><\/div>\n<div  class=\"col-xs bottom-xs flexbox image-group-bottom-3-img space-bottom-xs center-xs\"><a  class=\"left-img-anchor\" href=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\" target=\"_self\" data-cp-link=\"1\"><img  class=\"left-img shadow-large-black\" data-size=\"500x300\"><\/a> <a  class=\"center-img-anchor\" href=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\" target=\"_self\" data-cp-link=\"1\"><img  class=\"center-img shadow-large-black\" data-size=\"500x300\"><\/a> <a  class=\"right-img-anchor\" href=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\" target=\"_self\" data-cp-link=\"1\"><img  class=\"right-img shadow-large-black\" data-size=\"500x300\"><\/a><\/div>\n<\/div>\n<\/div>\n<\/div><div  id=\"les-prochaines-dates\" class=\"content-2 content-section content-section-spacing\" style=\"background-color: #ffffff; background-image: none;\" data-label=\"Les prochaines dates\" data-id=\"content--1\" data-export-id=\"content-2\" data-category=\"content\">\n<div  class=\"row middle-xs\">\n<div  class=\"col-sm-5 bg-image shadow-large-black\" style=\"background-image: url('https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-icone-sdm-1.jpg');\" data-bg=\"image\"><\/div>\n<div  class=\"col-sm-7 full-col-left-padding full-col-right-padding\">\n<div  class=\"row\">\n<div  class=\"space-bottom-small content-title-col\" data-type=\"column\">\n<h2  class=\"\">Les prochaines dates<\/h2>\n<p  class=\"\">Jeudi 23 avril \/\/ \u00ab Amour(s) Toujours (concert amoureux) \u00bb<br >19h \u2013 Moulin des Arts (Rognac)\n\n<br >(r\u00e9servations : 04 42 30 75 71)\n\n<br ><br >\nMercredi 29 avril \/\/ \u00ab Encore une chanson ! \u00bb\n<br >10h30 \u2013 Biblioth\u00e8que Molleg\u00e8s\n\n<br >(renseignements : 04.32.61.10.16)\n<br ><br >Lundi 4 mai&nbsp;\/\/ \u00ab Encore une chanson ! \u00bb\n<br >Ecole maternelle Peisson (Ventabren)\n<br ><br >Vendredi 26 juin \/\/&nbsp;\u00ab Encore une chanson ! \u00bb\n<br >Ecole maternelle Jean d\u2019Ormesson (Ventabren)<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div  id=\"images\" class=\"portfolio-4 content-section content-section-spacing-top\" style=\"background-color: #f5fafd;\" data-label=\"images\" data-id=\"portfolio-4\" data-export-id=\"portfolio-4\" data-category=\"portfolio\">\n<div  class=\"\">\n<div  class=\"row\" data-type=\"row\" data-fixed=\"true\">\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-DSC_6315_CIE_Claire-P_Oct2024-scaled-1.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/www.cielesondesmots.com\/wp-content\/uploads\/2025\/12\/cropped-P1156314.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-DSC09931-scaled-1.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/www.cielesondesmots.com\/wp-content\/uploads\/2025\/12\/cropped-P1156711.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-DSC09824-scaled-1.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/www.cielesondesmots.com\/wp-content\/uploads\/2025\/12\/cropped-P1156280.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-DSC09749_CIE_Claire-P_Oct2024-scaled-1.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-xs-12 col-sm-3 no-gutter-col\">\n<div  class=\"contentswap-effect\" data-hover-fx=\"portfolio-4\">\n<div  class=\"initial-image\"><img  decoding=\"async\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-DSC09999-scaled-2.jpg\" data-size=\"542x360\"><\/div>\n<div  class=\"overlay bg-color1\"><\/div>\n<div  class=\"swap-inner col-xs-12\">\n<div  class=\"row full-height-row middle-xs middle-sm\">\n<div  class=\"col-xs-12 text-center content-holder\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div  id=\"notre-quipe\" class=\"team-2 content-section content-section-spacing\" style=\"background-color: #f5fafd;\" data-label=\"notre quipe\" data-id=\"team--1\" data-export-id=\"team-2\" data-category=\"team\">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">Notre \u00e9quipe<\/h2>\n<\/div>\n<\/div>\n<div  class=\"row spaced-cols content-center-sm\" data-type=\"row\">\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"Claire Philippe-90\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-cropped-Claire-Philippe-90-scaled-1.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"\">Claire Philippe<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Com\u00e9dienne, metteuse en sc\u00e8ne, directrice artistique<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"M-Philippon-Portrait\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-M-Philippon-Portrait-scaled-1.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"font-500\">Matthieu Philippon<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Com\u00e9dien<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-cecile-petit.webp\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-cecile-petit.webp\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"font-500\">C\u00e9cile Petit<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Com\u00e9dienne-chanteuse<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-IMG_3622.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-IMG_3622.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"font-500\">Veronika Soboljevski<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">VIoloncelliste<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-IMG-20211002-WA0000-1.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-IMG-20211002-WA0000-1.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"font-500\">Marie-C\u00e9cile Gautier<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Pianiste<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-fred.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-fred.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"font-500\">Fr\u00e9d\u00e9ric Albertini<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Guitariste, bassiste<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-caroline-ruiz-HD-2021-03.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-caroline-ruiz-HD-2021-03.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"font-500\">Caroline Ruiz<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Metteur en sc\u00e8ne<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-IMG-20220508-WA0002-1.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-IMG-20220508-WA0002-1.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"\">Ad\u00e9lie Prin<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Dessinatrice<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-IMG-20221109-WA0000.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-IMG-20221109-WA0000.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"\">Maxence Vincendeau<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Com\u00e9dienne, metteuse en sc\u00e8ne, directrice artistique<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"cropped-cropped-vincent-3.jpg\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-cropped-vincent-3.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"\">Vincent Guibal<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Cr\u00e9ateur lumi\u00e8res<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div  class=\"col-sm-6 col-md-3\">\n<div  class=\"card y-move no-padding bordered\"><img  decoding=\"async\" class=\"face\" title=\"IMG_4108 OK COULEUR\" src=\"https:\/\/wcfuhbq.cluster121.hosting.ovh.net\/wp-content\/uploads\/2025\/11\/cropped-IMG_4108-OK-COULEUR-scaled-1.jpg\" alt=\"\">\n<div  class=\"col-padding-small col-padding-small-xs description-container\" data-type=\"column\">\n<h4  class=\"\">Micka\u00ebl Roche<\/h4>\n<p  class=\"small\" style=\"font-style: italic;\">Ing\u00e9nieur du son<\/p>\n\n<div  class=\"social-icons-group\" data-type=\"group\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div  id=\"contact-1\" class=\"contact-1 content-section content-section-spacing white-text\" data-label=\"Contact\" data-id=\"contact-1\" data-export-id=\"contact-1\" data-category=\"contact\" data-parallax-depth=\"20\">\n<div  class=\"gridContainer\">\n<div  class=\"row text-center\">\n<div  class=\"section-title-col\" data-type=\"column\">\n<h2  class=\"\">Nous contacter<\/h2>\n<\/div>\n<\/div>\n<div  class=\"row text-center\">\n<div  class=\"col-xs-12 col-sm-8 col-sm-offset-2 contact-form-wrapper inline-info\">\n<div  class=\"card large-padding\">\n<div  class=\"\" data-content-shortcode=\"mesmerize_contact_form shortcode=&quot;wpforms id=&amp;amp;quot;65&amp;amp;quot;&quot;\" data-editable=\"true\"><style id=\"wpforms-css-vars-65\">\n\t\t\t\t#wpforms-65 {\n\t\t\t\t--wpforms-container-padding: 0px;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-radius: 3px;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-65\"><form id=\"wpforms-form-65\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"65\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/33\" data-token=\"ef6aad11ac12c17a4c65e4be0cb5a1d0\" data-token-time=\"1778669929\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-65-field_5-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"5\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-65-field_5\" >Nom Votre E-mail<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-65-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-65-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-65-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-65-field_1-error\" required><label for=\"wpforms-65-field_1\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-65-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-65-field_1-last-error\" required><label for=\"wpforms-65-field_1-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-65-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-65-field_2\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-65-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-65-field_2-error\" required><\/div><div id=\"wpforms-65-field_4-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"4\"><fieldset><legend class=\"wpforms-field-label\">Votre demande <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-65-field_4\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-65-field_4_1\" name=\"wpforms[fields][4][]\" value=\"Demande de disponibilit\u00e9\" aria-errormessage=\"wpforms-65-field_4_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-65-field_4_1\">Demande de disponibilit\u00e9<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-65-field_4_2\" name=\"wpforms[fields][4][]\" value=\"Demande de devis\" aria-errormessage=\"wpforms-65-field_4_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-65-field_4_2\">Demande de devis<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-65-field_4_3\" name=\"wpforms[fields][4][]\" value=\"Demande dossier artistique\" aria-errormessage=\"wpforms-65-field_4_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-65-field_4_3\">Demande dossier artistique<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-65-field_4_4\" name=\"wpforms[fields][4][]\" value=\"Inscription Newsletter\" aria-errormessage=\"wpforms-65-field_4_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-65-field_4_4\">Inscription Newsletter<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-65-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-65-field_3\">Votre message<\/label><textarea id=\"wpforms-65-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-65-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-65-field_5-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-65-field_5-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-65-field_5-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"65\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/pages\/33\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-65\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.cielesondesmots.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Cie Le Son des Mots Un th\u00e9\u00e2tre de sens Les prochaines dates Jeudi 23 avril \/\/ \u00ab Amour(s) Toujours (concert amoureux) \u00bb19h \u2013 Moulin des Arts (Rognac) (r\u00e9servations : 04 42 30 75 71) Mercredi 29 avril \/\/ \u00ab Encore une chanson ! \u00bb 10h30 \u2013 Biblioth\u00e8que Molleg\u00e8s (renseignements : 04.32.61.10.16) Lundi 4 mai&nbsp;\/\/ \u00ab&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/www.cielesondesmots.com\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage.php","meta":{"footnotes":""},"class_list":["post-33","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/pages\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":26,"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/pages\/33\/revisions"}],"predecessor-version":[{"id":234,"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/pages\/33\/revisions\/234"}],"wp:attachment":[{"href":"https:\/\/www.cielesondesmots.com\/index.php\/wp-json\/wp\/v2\/media?parent=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}